{"id":7997,"date":"2026-01-17T08:41:20","date_gmt":"2026-01-17T06:41:20","guid":{"rendered":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg"},"modified":"2026-01-17T08:41:44","modified_gmt":"2026-01-17T06:41:44","slug":"5d322df1c677444304f52bb9ecfd81d1-2","status":"inherit","type":"attachment","link":"https:\/\/izvelies.eu\/ru\/5d322df1c677444304f52bb9ecfd81d1-2\/","title":{"rendered":"5d322df1c677444304f52bb9ecfd81d1"},"author":41,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5d322df1c677444304f52bb9ecfd81d1 - Izv\u0113lies.eu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5d322df1c677444304f52bb9ecfd81d1 - Izv\u0113lies.eu\" \/>\n<meta property=\"og:description\" content=\"Publicit\u0101ytes foto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Izv\u0113lies.eu\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-17T06:41:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg\",\"url\":\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg\",\"name\":\"5d322df1c677444304f52bb9ecfd81d1 - Izv\u0113lies.eu\",\"isPartOf\":{\"@id\":\"https:\/\/izvelies.eu\/#website\"},\"datePublished\":\"2026-01-17T06:41:20+00:00\",\"dateModified\":\"2026-01-17T06:41:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/izvelies.eu\/ru\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5d322df1c677444304f52bb9ecfd81d1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/izvelies.eu\/#website\",\"url\":\"https:\/\/izvelies.eu\/\",\"name\":\"Izv\u0113lies.eu\",\"description\":\"Izv\u0113lies.eu\",\"publisher\":{\"@id\":\"https:\/\/izvelies.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/izvelies.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/izvelies.eu\/#organization\",\"name\":\"Izv\u0113lies.eu\",\"url\":\"https:\/\/izvelies.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/izvelies.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/izvelies.eu\/wp-content\/uploads\/2015\/11\/logo.jpg\",\"contentUrl\":\"https:\/\/izvelies.eu\/wp-content\/uploads\/2015\/11\/logo.jpg\",\"width\":140,\"height\":140,\"caption\":\"Izv\u0113lies.eu\"},\"image\":{\"@id\":\"https:\/\/izvelies.eu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5d322df1c677444304f52bb9ecfd81d1 - Izv\u0113lies.eu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg","og_locale":"ru_RU","og_type":"article","og_title":"5d322df1c677444304f52bb9ecfd81d1 - Izv\u0113lies.eu","og_description":"Publicit\u0101ytes foto","og_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg","og_site_name":"Izv\u0113lies.eu","article_modified_time":"2026-01-17T06:41:44+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg","url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg","name":"5d322df1c677444304f52bb9ecfd81d1 - Izv\u0113lies.eu","isPartOf":{"@id":"https:\/\/izvelies.eu\/#website"},"datePublished":"2026-01-17T06:41:20+00:00","dateModified":"2026-01-17T06:41:44+00:00","breadcrumb":{"@id":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/izvelies.eu\/ru\/"},{"@type":"ListItem","position":2,"name":"5d322df1c677444304f52bb9ecfd81d1"}]},{"@type":"WebSite","@id":"https:\/\/izvelies.eu\/#website","url":"https:\/\/izvelies.eu\/","name":"Izv\u0113lies.eu","description":"Izv\u0113lies.eu","publisher":{"@id":"https:\/\/izvelies.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/izvelies.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/izvelies.eu\/#organization","name":"Izv\u0113lies.eu","url":"https:\/\/izvelies.eu\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/izvelies.eu\/#\/schema\/logo\/image\/","url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2015\/11\/logo.jpg","contentUrl":"https:\/\/izvelies.eu\/wp-content\/uploads\/2015\/11\/logo.jpg","width":140,"height":140,"caption":"Izv\u0113lies.eu"},"image":{"@id":"https:\/\/izvelies.eu\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-300x169.jpg 300w, https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-1024x576.jpg 1024w, https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-750x422.jpg 750w, https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Publicit\u0101ytes foto<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":675,"file":"2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg","filesize":90757,"sizes":{"medium":{"file":"5d322df1c677444304f52bb9ecfd81d1-300x169.jpg","width":300,"height":169,"filesize":7818,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-300x169.jpg"},"large":{"file":"5d322df1c677444304f52bb9ecfd81d1-1024x576.jpg","width":1024,"height":576,"filesize":63898,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-1024x576.jpg"},"thumbnail":{"file":"5d322df1c677444304f52bb9ecfd81d1-150x150.jpg","width":150,"height":150,"filesize":4858,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-150x150.jpg"},"post-thumbnail":{"file":"5d322df1c677444304f52bb9ecfd81d1-125x125.jpg","width":125,"height":125,"filesize":3689,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-125x125.jpg"},"valenti-360-240":{"file":"5d322df1c677444304f52bb9ecfd81d1-360x240.jpg","width":360,"height":240,"filesize":12528,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-360x240.jpg"},"valenti-480-320":{"file":"5d322df1c677444304f52bb9ecfd81d1-480x320.jpg","width":480,"height":320,"filesize":20390,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-480x320.jpg"},"valenti-720-480":{"file":"5d322df1c677444304f52bb9ecfd81d1-720x480.jpg","width":720,"height":480,"filesize":41955,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-720x480.jpg"},"valenti-480-256":{"file":"5d322df1c677444304f52bb9ecfd81d1-480x256.jpg","width":480,"height":256,"filesize":15461,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-480x256.jpg"},"valenti-600-320":{"file":"5d322df1c677444304f52bb9ecfd81d1-600x320.jpg","width":600,"height":320,"filesize":22546,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-600x320.jpg"},"valenti-750-400":{"file":"5d322df1c677444304f52bb9ecfd81d1-750x400.jpg","width":750,"height":400,"filesize":34029,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-750x400.jpg"},"valenti-1200-640":{"file":"5d322df1c677444304f52bb9ecfd81d1-1200x640.jpg","width":1200,"height":640,"filesize":94193,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-1200x640.jpg"},"valenti-750-full":{"file":"5d322df1c677444304f52bb9ecfd81d1-750x422.jpg","width":750,"height":422,"filesize":36114,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1-750x422.jpg"},"full":{"file":"5d322df1c677444304f52bb9ecfd81d1.jpg","width":1200,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/izvelies.eu\/wp-content\/uploads\/2026\/01\/5d322df1c677444304f52bb9ecfd81d1.jpg","_links":{"self":[{"href":"https:\/\/izvelies.eu\/ru\/wp-json\/wp\/v2\/media\/7997"}],"collection":[{"href":"https:\/\/izvelies.eu\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/izvelies.eu\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/izvelies.eu\/ru\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/izvelies.eu\/ru\/wp-json\/wp\/v2\/comments?post=7997"}]}}